{"id":62569,"date":"2024-11-08T13:43:07","date_gmt":"2024-11-08T11:43:07","guid":{"rendered":"https:\/\/cycladic.gr\/?post_type=event&#038;p=62569"},"modified":"2026-03-27T17:22:55","modified_gmt":"2026-03-27T15:22:55","slug":"day-trip-to-nemea","status":"publish","type":"event","link":"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/","title":{"rendered":"Day Trip to Nemea"},"content":{"rendered":"<section class=\"section HeaderBlock \">\n  <header>\n  <h1 class=\"title\">Day Trip to Nemea<\/h1>  <p class=\"data\">YOUNG PATRONS<\/p>  <p class=\"data\">NOVEMBER 2, 2024<\/p><\/header>          <div \n      class=\"imgWithCaption card  \" \n          >\n        <figure class=\"image ratio-L_16-9\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1150-scaled.jpeg\" alt=\"\" srcset=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1150-225x300.jpeg 225w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1150-768x1024.jpeg 768w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1150-1152x1536.jpeg 1152w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1150-1536x2048.jpeg 1536w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1150-600x800.jpeg 600w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1150-scaled.jpeg 1920w\" sizes=\"100vw\" \/>\n          <\/figure>\n        \n  <\/div>\n\n  \n  <\/section>\n\n\n\n\n<section class=\"section ContentBlock\" >\n    \n  <div class=\"main \">\n    <div class=\"left sticky\">\n              <div class=\"contentSidebar\">\n  \n    <div class=\"textSidebar\">\n    Cycladic Young Patrons had the privilege of enjoying a day trip to Nemea, the largest viticultural zone in Greece.\n  <\/div>\n    \n   \n<\/div>\n\n          <\/div>\n    <div class=\"right \">\n                         <div class=\"mainText\">\n<p>Just a mere hour and a half from Athens lies a place seemingly blessed by Mount Olympus.<\/p>\n<p>Hercules showed his early feats of bravery here, while Demeter sought solace and comfort.\u00a0Zeus\u2019\u00a0temple was erected here since the 4th century BC. But most notably, it was\u00a0Dionysus\u00a0who, according to legend, sent\u00a0his son, Phlias,\u00a0to plant vineyards throughout Nemea,\u00a0creating the country\u2019s premier wine-producing region.<\/p>\n\n  <!-- Rich Text Editor Start -->\n  <\/div>\n\n                  <\/div>\n  <\/div>\n<\/section>\n\n\n\n<section class=\"section ContentBlock\">\n    <div class=\"ImageGrid grid-3\">\n    <div class=\"swiper-wrapper\">\n              \n                \n                           \n\n              <div \n      class=\"imgWithCaption card swiper-slide zoom\" \n              data-src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-scaled.jpeg\" data-sub-html=\".info\"\n          >\n        <figure class=\"image ratio-1-1\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-576x1024.jpeg\" alt=\"\" srcset=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-169x300.jpeg 169w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-576x1024.jpeg 576w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-768x1365.jpeg 768w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-864x1536.jpeg 864w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-1152x2048.jpeg 1152w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-600x1066.jpeg 600w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1146-scaled.jpeg 1440w\" sizes=\"(min-width: 768px) 33vw, 100vw\" \/>\n          <\/figure>\n        <div class=\"info\">\n  <div class=\"number\">01<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n              \n                \n                           \n\n              <div \n      class=\"imgWithCaption card swiper-slide zoom\" \n              data-src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-scaled.jpg\" data-sub-html=\".info\"\n          >\n        <figure class=\"image ratio-1-1\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-768x1024.jpg\" alt=\"\" srcset=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-225x300.jpg 225w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-768x1024.jpg 768w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-1152x1536.jpg 1152w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-1536x2048.jpg 1536w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-600x800.jpg 600w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_3088_VSCO-scaled.jpg 1920w\" sizes=\"(min-width: 768px) 33vw, 100vw\" \/>\n          <\/figure>\n        <div class=\"info\">\n  <div class=\"number\">02<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n              \n                \n                           \n\n              <div \n      class=\"imgWithCaption card swiper-slide zoom\" \n              data-src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-scaled.jpeg\" data-sub-html=\".info\"\n          >\n        <figure class=\"image ratio-1-1\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-768x1024.jpeg\" alt=\"\" srcset=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-225x300.jpeg 225w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-768x1024.jpeg 768w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-1152x1536.jpeg 1152w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-1536x2048.jpeg 1536w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-600x800.jpeg 600w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1189-scaled.jpeg 1920w\" sizes=\"(min-width: 768px) 33vw, 100vw\" \/>\n          <\/figure>\n        <div class=\"info\">\n  <div class=\"number\">03<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n              \n                \n                           \n\n              <div \n      class=\"imgWithCaption card swiper-slide zoom\" \n              data-src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-scaled.jpeg\" data-sub-html=\".info\"\n          >\n        <figure class=\"image ratio-1-1\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-768x1024.jpeg\" alt=\"\" srcset=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-225x300.jpeg 225w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-768x1024.jpeg 768w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-1152x1536.jpeg 1152w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-1536x2048.jpeg 1536w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-600x800.jpeg 600w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1204-scaled.jpeg 1920w\" sizes=\"(min-width: 768px) 33vw, 100vw\" \/>\n          <\/figure>\n        <div class=\"info\">\n  <div class=\"number\">04<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n              \n                \n                           \n\n              <div \n      class=\"imgWithCaption card swiper-slide zoom\" \n              data-src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241.jpg\" data-sub-html=\".info\"\n          >\n        <figure class=\"image ratio-1-1\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241-572x1024.jpg\" alt=\"\" srcset=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241-168x300.jpg 168w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241-572x1024.jpg 572w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241-768x1375.jpg 768w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241-858x1536.jpg 858w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241-600x1074.jpg 600w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1241.jpg 1125w\" sizes=\"(min-width: 768px) 33vw, 100vw\" \/>\n          <\/figure>\n        <div class=\"info\">\n  <div class=\"number\">05<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n              \n                \n                           \n\n              <div \n      class=\"imgWithCaption card swiper-slide zoom\" \n              data-src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243.jpg\" data-sub-html=\".info\"\n          >\n        <figure class=\"image ratio-1-1\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243-579x1024.jpg\" alt=\"\" srcset=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243-170x300.jpg 170w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243-579x1024.jpg 579w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243-768x1359.jpg 768w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243-868x1536.jpg 868w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243-600x1061.jpg 600w, https:\/\/cycladic.gr\/wp-content\/uploads\/2024\/11\/IMG_1243.jpg 1125w\" sizes=\"(min-width: 768px) 33vw, 100vw\" \/>\n          <\/figure>\n        <div class=\"info\">\n  <div class=\"number\">06<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n          <\/div>\n  <\/div>\n  <div class=\"ImageGridCaptions\">\n  <div class=\"swiper-wrapper\"> \n                            <div \n      class=\"imgWithCaption card swiper-slide \" \n          >\n        <div class=\"info\">\n  <div class=\"number\">01<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n                           <div \n      class=\"imgWithCaption card swiper-slide \" \n          >\n        <div class=\"info\">\n  <div class=\"number\">02<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n                           <div \n      class=\"imgWithCaption card swiper-slide \" \n          >\n        <div class=\"info\">\n  <div class=\"number\">03<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n                           <div \n      class=\"imgWithCaption card swiper-slide \" \n          >\n        <div class=\"info\">\n  <div class=\"number\">04<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n                           <div \n      class=\"imgWithCaption card swiper-slide \" \n          >\n        <div class=\"info\">\n  <div class=\"number\">05<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n                           <div \n      class=\"imgWithCaption card swiper-slide \" \n          >\n        <div class=\"info\">\n  <div class=\"number\">06<\/div>  <div class=\"caption\">Day Trip to Nemea<\/div>  <div class=\"text\">Photo \u00a9 Museum of Cycladic Art<\/div><\/div>\n\n  <\/div>\n\n        \n    <\/div>\n    <div class=\"swiper-buttons\">\n      <button class=\"swiper-button-prev button quaternary standard\" aria-label=\"Previous Slide\">\n        <span class=\"default\">\n          <svg class=\"icon-svg \"\n  aria-hidden=\"true\"\n  role=\"presentation\"\n  shape-rendering=\"geometricPrecision\"\n   width=\"24\"    height=\"24\" >\n  <use class=\"icon-arrow-left\" xlink:href=\"\/wp-content\/themes\/mkt\/dist\/assets\/images\/sprite.svg#icon-arrow-left\"><\/use>\n<\/svg>\n \n        <\/span>\n      <\/button>\n      <button class=\"swiper-button-next button quaternary standard\" aria-label=\"Next Slide\">\n        <span class=\"default\">\n          <svg class=\"icon-svg \"\n  aria-hidden=\"true\"\n  role=\"presentation\"\n  shape-rendering=\"geometricPrecision\"\n   width=\"24\"    height=\"24\" >\n  <use class=\"icon-arrow-right\" xlink:href=\"\/wp-content\/themes\/mkt\/dist\/assets\/images\/sprite.svg#icon-arrow-right\"><\/use>\n<\/svg>\n \n        <\/span>\n      <\/button>\n    <\/div>\n  <\/div>\n<\/section>\n\n\n\n\n\n<section class=\"section ContentBlock\n   \">\n  \n\n  <div class=\"ListBlock gridcard-1\">\n  \n     \n          \n       \n         \n      \n        <div class=\"card colored horizontal orange\">\n    <div class=\"image\">\n    <svg class=\"icon-svg \"\n  aria-hidden=\"true\"\n  role=\"presentation\"\n  shape-rendering=\"geometricPrecision\"\n   width=\"200\"    height=\"200\" >\n  <use class=\"icon-cardFriend\" xlink:href=\"\/wp-content\/themes\/mkt\/dist\/assets\/images\/sprite.svg#icon-cardFriend\"><\/use>\n<\/svg>\n  <\/div>\n    <div class=\"info\">\n    <h3 class=\"title\"><a href=\"https:\/\/cycladic.gr\/en\/memberships\/young-patrons\/\">Young Patrons<\/a><\/h3>    <p class=\"subtitle\">250\u20ac annually<\/p>    <div class=\"text\">The Young Patrons category is a addressed to young people under 45 years old with a curated program of activities in Greece and abroad<\/div>        \n      <a class=\"button arrowRight secondary reversed\" href=\"https:\/\/cycladic.gr\/en\/memberships\/young-patrons\/\" \n        aria-label=\"LEARN MORE ABOUT: Young Patrons\"\n          >\n  \n  <span class=\"default\">\n            <span>LEARN MORE<\/span>\n              <svg class=\"icon-svg \"\n  aria-hidden=\"true\"\n  role=\"presentation\"\n  shape-rendering=\"geometricPrecision\"\n   width=\"24\"    height=\"24\" >\n  <use class=\"icon-arrow-right\" xlink:href=\"\/wp-content\/themes\/mkt\/dist\/assets\/images\/sprite.svg#icon-arrow-right\"><\/use>\n<\/svg>\n      <\/span>\n  <span class=\"double\" aria-hidden=\"true\">\n            <span>LEARN MORE<\/span>\n               <svg class=\"icon-svg \"\n  aria-hidden=\"true\"\n  role=\"presentation\"\n  shape-rendering=\"geometricPrecision\"\n   width=\"24\"    height=\"24\" >\n  <use class=\"icon-arrow-right\" xlink:href=\"\/wp-content\/themes\/mkt\/dist\/assets\/images\/sprite.svg#icon-arrow-right\"><\/use>\n<\/svg>\n      <\/span>\n\n    <\/a>\n        <\/div>\n<\/div>      \n    \n  <\/div>\n\n<\/section>\n\n\n<section class=\"section ContentBlock\"  >\n        <div class=\"Credits\">\n    <div class=\"title\">Strategic Patner<\/div>    <div class=\"list\">\n                                      <div \n      class=\"imgWithCaption card  \" \n          >\n        <figure class=\"image ratio-L_2-1\">\n            <a href=\"https:\/\/www.eurolife.gr\/el-gr\/?gclid=CjwKCAjwt52mBhB5EiwA05YKo5wlocVjflGlXpF-v1nIr_Ab6AoegGK1HI4I0Ulyz-xNN-egaiSf5BoC6PcQAvD_BwE\"  aria-label=\"\u0399\u03c3\u03c4\u03bf\u03c3\u03b5\u03bb\u03af\u03b4\u03b1 Eurolife\">\n              <img decoding=\"async\" src=\"https:\/\/cycladic.gr\/wp-content\/uploads\/2023\/07\/Eurolife_logo_BW.jpg\" alt=\"\" srcset=\"\"  \/>\n            <\/a>\n         \n          <\/figure>\n        \n  <\/div>\n\n            <\/div>\n  <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":19592,"featured_media":0,"menu_order":0,"template":"","audience":[1087,1122],"class_list":["post-62569","event","type-event","status-publish","hentry","audience-young-patrons-en","audience-filoi-en"],"acf":{"start_date":"20241102","end_date":"20241102","overide_text":"","Type":"single_date","single_date_time":null,"multiple_dates":null,"multiple_dates_time":null,"weekdays_range":null,"ongoing":"Ongoing","upon_request":"Upon request"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Day Trip to Nemea - Museum of Cycladic Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Day Trip to Nemea - Museum of Cycladic Art\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/\" \/>\n<meta property=\"og:site_name\" content=\"Museum of Cycladic Art\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CycladicArtMuseum\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T15:22:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cycladic.gr\\\/en\\\/draseis\\\/day-trip-to-nemea\\\/\",\"url\":\"https:\\\/\\\/cycladic.gr\\\/en\\\/draseis\\\/day-trip-to-nemea\\\/\",\"name\":\"Day Trip to Nemea - Museum of Cycladic Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cycladic.gr\\\/#website\"},\"datePublished\":\"2024-11-08T11:43:07+00:00\",\"dateModified\":\"2026-03-27T15:22:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cycladic.gr\\\/en\\\/draseis\\\/day-trip-to-nemea\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cycladic.gr\\\/en\\\/draseis\\\/day-trip-to-nemea\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cycladic.gr\\\/en\\\/draseis\\\/day-trip-to-nemea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/cycladic.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/cycladic.gr\\\/ekdiloseis\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Day Trip to Nemea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cycladic.gr\\\/#website\",\"url\":\"https:\\\/\\\/cycladic.gr\\\/\",\"name\":\"Museum of Cycladic Art\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cycladic.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Day Trip to Nemea - Museum of Cycladic Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/","og_locale":"en_US","og_type":"article","og_title":"Day Trip to Nemea - Museum of Cycladic Art","og_url":"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/","og_site_name":"Museum of Cycladic Art","article_publisher":"https:\/\/www.facebook.com\/CycladicArtMuseum\/","article_modified_time":"2026-03-27T15:22:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/","url":"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/","name":"Day Trip to Nemea - Museum of Cycladic Art","isPartOf":{"@id":"https:\/\/cycladic.gr\/#website"},"datePublished":"2024-11-08T11:43:07+00:00","dateModified":"2026-03-27T15:22:55+00:00","breadcrumb":{"@id":"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cycladic.gr\/en\/draseis\/day-trip-to-nemea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/cycladic.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/cycladic.gr\/ekdiloseis\/"},{"@type":"ListItem","position":3,"name":"Day Trip to Nemea"}]},{"@type":"WebSite","@id":"https:\/\/cycladic.gr\/#website","url":"https:\/\/cycladic.gr\/","name":"Museum of Cycladic Art","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cycladic.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cycladic.gr\/en\/wp-json\/wp\/v2\/event\/62569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cycladic.gr\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/cycladic.gr\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/cycladic.gr\/en\/wp-json\/wp\/v2\/users\/19592"}],"wp:attachment":[{"href":"https:\/\/cycladic.gr\/en\/wp-json\/wp\/v2\/media?parent=62569"}],"wp:term":[{"taxonomy":"audience","embeddable":true,"href":"https:\/\/cycladic.gr\/en\/wp-json\/wp\/v2\/audience?post=62569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}